{"id":3539,"date":"1970-01-01T00:00:00","date_gmt":"1970-01-01T00:00:00","guid":{"rendered":"http:\/\/sanjorgelibreria.com\/?post_type=product&#038;p=3539"},"modified":"2026-01-26T16:15:33","modified_gmt":"2026-01-26T16:15:33","slug":"tempera-alba-clasico-x-unidad-color-negra","status":"publish","type":"product","link":"https:\/\/sanjorgelibreria.com\/index.php\/producto\/tempera-alba-clasico-x-unidad-color-negra\/","title":{"rendered":"TEMPERA ALBA CLASICO X UNIDAD COLOR NEGRA"},"content":{"rendered":"<p>tempera escolar en color<\/p>\n","protected":false},"excerpt":{"rendered":"<p>tempera escolar en color<\/p>\n","protected":false},"featured_media":9604,"template":"","meta":[],"product_brand":[],"product_cat":[454,20,413],"product_tag":[],"berocket_brand":[504],"class_list":{"0":"post-3539","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-en-cajas","7":"product_cat-libreria-escolar","8":"product_cat-temperas-libreria-escolar","9":"berocket_brand-alba","11":"first","12":"instock","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"tempera escolar en color\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/sanjorgelibreria.com\/index.php\/producto\/tempera-alba-clasico-x-unidad-color-negra\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"SAN JORGE - Libreria Comercial, Librer\u00eda Escolar y Jugueter\u00eda\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"TEMPERA ALBA CLASICO X UNIDAD COLOR NEGRA - SAN JORGE\" \/>\n\t\t<meta property=\"og:description\" content=\"tempera escolar en color\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/sanjorgelibreria.com\/index.php\/producto\/tempera-alba-clasico-x-unidad-color-negra\/\" \/>\n\t\t<meta property=\"og:image\" content=\"https:\/\/sanjorgelibreria.com\/wp-content\/uploads\/2022\/02\/cropped-San-Jorge-min-1.png\" \/>\n\t\t<meta property=\"og:image:secure_url\" content=\"https:\/\/sanjorgelibreria.com\/wp-content\/uploads\/2022\/02\/cropped-San-Jorge-min-1.png\" \/>\n\t\t<meta property=\"article:published_time\" content=\"1970-01-01T00:00:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-01-26T16:15:33+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"TEMPERA ALBA CLASICO X UNIDAD COLOR NEGRA - SAN JORGE\" \/>\n\t\t<meta name=\"twitter:description\" content=\"tempera escolar en color\" \/>\n\t\t<meta name=\"twitter:image\" content=\"https:\/\/sanjorgelibreria.com\/wp-content\/uploads\/2022\/02\/cropped-San-Jorge-min-1.png\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/sanjorgelibreria.com\\\/index.php\\\/producto\\\/tempera-alba-clasico-x-unidad-color-negra\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sanjorgelibreria.com#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/sanjorgelibreria.com\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sanjorgelibreria.com\\\/index.php\\\/tienda\\\/#listItem\",\"name\":\"Tienda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sanjorgelibreria.com\\\/index.php\\\/tienda\\\/#listItem\",\"position\":2,\"name\":\"Tienda\",\"item\":\"https:\\\/\\\/sanjorgelibreria.com\\\/index.php\\\/tienda\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sanjorgelibreria.com\\\/index.php\\\/categoria-producto\\\/libreria-escolar\\\/#listItem\",\"name\":\"LIBRERIA ESCOLAR\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sanjorgelibreria.com#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sanjorgelibreria.com\\\/index.php\\\/categoria-producto\\\/libreria-escolar\\\/#listItem\",\"position\":3,\"name\":\"LIBRERIA ESCOLAR\",\"item\":\"https:\\\/\\\/sanjorgelibreria.com\\\/index.php\\\/categoria-producto\\\/libreria-escolar\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sanjorgelibreria.com\\\/index.php\\\/categoria-producto\\\/libreria-escolar\\\/temperas-libreria-escolar\\\/#listItem\",\"name\":\"TEMPERAS\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sanjorgelibreria.com\\\/index.php\\\/tienda\\\/#listItem\",\"name\":\"Tienda\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sanjorgelibreria.com\\\/index.php\\\/categoria-producto\\\/libreria-escolar\\\/temperas-libreria-escolar\\\/#listItem\",\"position\":4,\"name\":\"TEMPERAS\",\"item\":\"https:\\\/\\\/sanjorgelibreria.com\\\/index.php\\\/categoria-producto\\\/libreria-escolar\\\/temperas-libreria-escolar\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sanjorgelibreria.com\\\/index.php\\\/categoria-producto\\\/libreria-escolar\\\/temperas-libreria-escolar\\\/en-cajas\\\/#listItem\",\"name\":\"EN CAJAS\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sanjorgelibreria.com\\\/index.php\\\/categoria-producto\\\/libreria-escolar\\\/#listItem\",\"name\":\"LIBRERIA ESCOLAR\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sanjorgelibreria.com\\\/index.php\\\/categoria-producto\\\/libreria-escolar\\\/temperas-libreria-escolar\\\/en-cajas\\\/#listItem\",\"position\":5,\"name\":\"EN CAJAS\",\"item\":\"https:\\\/\\\/sanjorgelibreria.com\\\/index.php\\\/categoria-producto\\\/libreria-escolar\\\/temperas-libreria-escolar\\\/en-cajas\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sanjorgelibreria.com\\\/index.php\\\/producto\\\/tempera-alba-clasico-x-unidad-color-negra\\\/#listItem\",\"name\":\"TEMPERA ALBA CLASICO X UNIDAD COLOR NEGRA\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sanjorgelibreria.com\\\/index.php\\\/categoria-producto\\\/libreria-escolar\\\/temperas-libreria-escolar\\\/#listItem\",\"name\":\"TEMPERAS\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sanjorgelibreria.com\\\/index.php\\\/producto\\\/tempera-alba-clasico-x-unidad-color-negra\\\/#listItem\",\"position\":6,\"name\":\"TEMPERA ALBA CLASICO X UNIDAD COLOR NEGRA\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/sanjorgelibreria.com\\\/index.php\\\/categoria-producto\\\/libreria-escolar\\\/temperas-libreria-escolar\\\/en-cajas\\\/#listItem\",\"name\":\"EN CAJAS\"}}]},{\"@type\":\"ItemPage\",\"@id\":\"https:\\\/\\\/sanjorgelibreria.com\\\/index.php\\\/producto\\\/tempera-alba-clasico-x-unidad-color-negra\\\/#itempage\",\"url\":\"https:\\\/\\\/sanjorgelibreria.com\\\/index.php\\\/producto\\\/tempera-alba-clasico-x-unidad-color-negra\\\/\",\"name\":\"TEMPERA ALBA CLASICO X UNIDAD COLOR NEGRA - SAN JORGE\",\"description\":\"tempera escolar en color\",\"inLanguage\":\"es-AR\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/sanjorgelibreria.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/sanjorgelibreria.com\\\/index.php\\\/producto\\\/tempera-alba-clasico-x-unidad-color-negra\\\/#breadcrumblist\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/sanjorgelibreria.com\\\/wp-content\\\/uploads\\\/2022\\\/01\\\/clasicas-sueltas.png\",\"@id\":\"https:\\\/\\\/sanjorgelibreria.com\\\/index.php\\\/producto\\\/tempera-alba-clasico-x-unidad-color-negra\\\/#mainImage\",\"width\":450,\"height\":450},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/sanjorgelibreria.com\\\/index.php\\\/producto\\\/tempera-alba-clasico-x-unidad-color-negra\\\/#mainImage\"},\"datePublished\":\"1970-01-01T00:00:00+00:00\",\"dateModified\":\"2026-01-26T16:15:33+00:00\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/sanjorgelibreria.com\\\/#organization\",\"name\":\"Libreria San Jorge\",\"description\":\"Libreria Comercial, Librer\\u00eda Escolar y Jugueter\\u00eda\",\"url\":\"https:\\\/\\\/sanjorgelibreria.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/sanjorgelibreria.com\\\/wp-content\\\/uploads\\\/2022\\\/02\\\/cropped-San-Jorge-min-1.png\",\"@id\":\"https:\\\/\\\/sanjorgelibreria.com\\\/index.php\\\/producto\\\/tempera-alba-clasico-x-unidad-color-negra\\\/#organizationLogo\",\"width\":361,\"height\":78},\"image\":{\"@id\":\"https:\\\/\\\/sanjorgelibreria.com\\\/index.php\\\/producto\\\/tempera-alba-clasico-x-unidad-color-negra\\\/#organizationLogo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/sanjorgelibreria.com\\\/#website\",\"url\":\"https:\\\/\\\/sanjorgelibreria.com\\\/\",\"name\":\"SAN JORGE\",\"description\":\"Libreria Comercial, Librer\\u00eda Escolar y Jugueter\\u00eda\",\"inLanguage\":\"es-AR\",\"publisher\":{\"@id\":\"https:\\\/\\\/sanjorgelibreria.com\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"TEMPERA ALBA CLASICO X UNIDAD COLOR NEGRA - SAN JORGE","description":"tempera escolar en color","canonical_url":"https:\/\/sanjorgelibreria.com\/index.php\/producto\/tempera-alba-clasico-x-unidad-color-negra\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/sanjorgelibreria.com\/index.php\/producto\/tempera-alba-clasico-x-unidad-color-negra\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/sanjorgelibreria.com#listItem","position":1,"name":"Home","item":"https:\/\/sanjorgelibreria.com","nextItem":{"@type":"ListItem","@id":"https:\/\/sanjorgelibreria.com\/index.php\/tienda\/#listItem","name":"Tienda"}},{"@type":"ListItem","@id":"https:\/\/sanjorgelibreria.com\/index.php\/tienda\/#listItem","position":2,"name":"Tienda","item":"https:\/\/sanjorgelibreria.com\/index.php\/tienda\/","nextItem":{"@type":"ListItem","@id":"https:\/\/sanjorgelibreria.com\/index.php\/categoria-producto\/libreria-escolar\/#listItem","name":"LIBRERIA ESCOLAR"},"previousItem":{"@type":"ListItem","@id":"https:\/\/sanjorgelibreria.com#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/sanjorgelibreria.com\/index.php\/categoria-producto\/libreria-escolar\/#listItem","position":3,"name":"LIBRERIA ESCOLAR","item":"https:\/\/sanjorgelibreria.com\/index.php\/categoria-producto\/libreria-escolar\/","nextItem":{"@type":"ListItem","@id":"https:\/\/sanjorgelibreria.com\/index.php\/categoria-producto\/libreria-escolar\/temperas-libreria-escolar\/#listItem","name":"TEMPERAS"},"previousItem":{"@type":"ListItem","@id":"https:\/\/sanjorgelibreria.com\/index.php\/tienda\/#listItem","name":"Tienda"}},{"@type":"ListItem","@id":"https:\/\/sanjorgelibreria.com\/index.php\/categoria-producto\/libreria-escolar\/temperas-libreria-escolar\/#listItem","position":4,"name":"TEMPERAS","item":"https:\/\/sanjorgelibreria.com\/index.php\/categoria-producto\/libreria-escolar\/temperas-libreria-escolar\/","nextItem":{"@type":"ListItem","@id":"https:\/\/sanjorgelibreria.com\/index.php\/categoria-producto\/libreria-escolar\/temperas-libreria-escolar\/en-cajas\/#listItem","name":"EN CAJAS"},"previousItem":{"@type":"ListItem","@id":"https:\/\/sanjorgelibreria.com\/index.php\/categoria-producto\/libreria-escolar\/#listItem","name":"LIBRERIA ESCOLAR"}},{"@type":"ListItem","@id":"https:\/\/sanjorgelibreria.com\/index.php\/categoria-producto\/libreria-escolar\/temperas-libreria-escolar\/en-cajas\/#listItem","position":5,"name":"EN CAJAS","item":"https:\/\/sanjorgelibreria.com\/index.php\/categoria-producto\/libreria-escolar\/temperas-libreria-escolar\/en-cajas\/","nextItem":{"@type":"ListItem","@id":"https:\/\/sanjorgelibreria.com\/index.php\/producto\/tempera-alba-clasico-x-unidad-color-negra\/#listItem","name":"TEMPERA ALBA CLASICO X UNIDAD COLOR NEGRA"},"previousItem":{"@type":"ListItem","@id":"https:\/\/sanjorgelibreria.com\/index.php\/categoria-producto\/libreria-escolar\/temperas-libreria-escolar\/#listItem","name":"TEMPERAS"}},{"@type":"ListItem","@id":"https:\/\/sanjorgelibreria.com\/index.php\/producto\/tempera-alba-clasico-x-unidad-color-negra\/#listItem","position":6,"name":"TEMPERA ALBA CLASICO X UNIDAD COLOR NEGRA","previousItem":{"@type":"ListItem","@id":"https:\/\/sanjorgelibreria.com\/index.php\/categoria-producto\/libreria-escolar\/temperas-libreria-escolar\/en-cajas\/#listItem","name":"EN CAJAS"}}]},{"@type":"ItemPage","@id":"https:\/\/sanjorgelibreria.com\/index.php\/producto\/tempera-alba-clasico-x-unidad-color-negra\/#itempage","url":"https:\/\/sanjorgelibreria.com\/index.php\/producto\/tempera-alba-clasico-x-unidad-color-negra\/","name":"TEMPERA ALBA CLASICO X UNIDAD COLOR NEGRA - SAN JORGE","description":"tempera escolar en color","inLanguage":"es-AR","isPartOf":{"@id":"https:\/\/sanjorgelibreria.com\/#website"},"breadcrumb":{"@id":"https:\/\/sanjorgelibreria.com\/index.php\/producto\/tempera-alba-clasico-x-unidad-color-negra\/#breadcrumblist"},"image":{"@type":"ImageObject","url":"https:\/\/sanjorgelibreria.com\/wp-content\/uploads\/2022\/01\/clasicas-sueltas.png","@id":"https:\/\/sanjorgelibreria.com\/index.php\/producto\/tempera-alba-clasico-x-unidad-color-negra\/#mainImage","width":450,"height":450},"primaryImageOfPage":{"@id":"https:\/\/sanjorgelibreria.com\/index.php\/producto\/tempera-alba-clasico-x-unidad-color-negra\/#mainImage"},"datePublished":"1970-01-01T00:00:00+00:00","dateModified":"2026-01-26T16:15:33+00:00"},{"@type":"Organization","@id":"https:\/\/sanjorgelibreria.com\/#organization","name":"Libreria San Jorge","description":"Libreria Comercial, Librer\u00eda Escolar y Jugueter\u00eda","url":"https:\/\/sanjorgelibreria.com\/","logo":{"@type":"ImageObject","url":"https:\/\/sanjorgelibreria.com\/wp-content\/uploads\/2022\/02\/cropped-San-Jorge-min-1.png","@id":"https:\/\/sanjorgelibreria.com\/index.php\/producto\/tempera-alba-clasico-x-unidad-color-negra\/#organizationLogo","width":361,"height":78},"image":{"@id":"https:\/\/sanjorgelibreria.com\/index.php\/producto\/tempera-alba-clasico-x-unidad-color-negra\/#organizationLogo"}},{"@type":"WebSite","@id":"https:\/\/sanjorgelibreria.com\/#website","url":"https:\/\/sanjorgelibreria.com\/","name":"SAN JORGE","description":"Libreria Comercial, Librer\u00eda Escolar y Jugueter\u00eda","inLanguage":"es-AR","publisher":{"@id":"https:\/\/sanjorgelibreria.com\/#organization"}}]},"og:locale":"es_ES","og:site_name":"SAN JORGE - Libreria Comercial, Librer\u00eda Escolar y Jugueter\u00eda","og:type":"article","og:title":"TEMPERA ALBA CLASICO X UNIDAD COLOR NEGRA - SAN JORGE","og:description":"tempera escolar en color","og:url":"https:\/\/sanjorgelibreria.com\/index.php\/producto\/tempera-alba-clasico-x-unidad-color-negra\/","og:image":"https:\/\/sanjorgelibreria.com\/wp-content\/uploads\/2022\/02\/cropped-San-Jorge-min-1.png","og:image:secure_url":"https:\/\/sanjorgelibreria.com\/wp-content\/uploads\/2022\/02\/cropped-San-Jorge-min-1.png","article:published_time":"1970-01-01T00:00:00+00:00","article:modified_time":"2026-01-26T16:15:33+00:00","twitter:card":"summary","twitter:title":"TEMPERA ALBA CLASICO X UNIDAD COLOR NEGRA - SAN JORGE","twitter:description":"tempera escolar en color","twitter:image":"https:\/\/sanjorgelibreria.com\/wp-content\/uploads\/2022\/02\/cropped-San-Jorge-min-1.png"},"aioseo_meta_data":{"post_id":"3539","title":null,"description":null,"keywords":null,"keyphrases":{"focus":[],"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":null,"isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-01-31 17:25:44","updated":"2026-01-26 22:25:56","focus_keyword":null,"additional_keywords":null,"truseo_locale":null,"seo_analyzer_scan_date":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/sanjorgelibreria.com\" title=\"Home\">Home<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/sanjorgelibreria.com\/index.php\/tienda\/\" title=\"Tienda\">Tienda<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/sanjorgelibreria.com\/index.php\/categoria-producto\/libreria-escolar\/\" title=\"LIBRERIA ESCOLAR\">LIBRERIA ESCOLAR<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/sanjorgelibreria.com\/index.php\/categoria-producto\/libreria-escolar\/temperas-libreria-escolar\/\" title=\"TEMPERAS\">TEMPERAS<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/sanjorgelibreria.com\/index.php\/categoria-producto\/libreria-escolar\/temperas-libreria-escolar\/en-cajas\/\" title=\"EN CAJAS\">EN CAJAS<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tTEMPERA ALBA CLASICO X UNIDAD COLOR NEGRA\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Home","link":"https:\/\/sanjorgelibreria.com"},{"label":"Tienda","link":"https:\/\/sanjorgelibreria.com\/index.php\/tienda\/"},{"label":"LIBRERIA ESCOLAR","link":"https:\/\/sanjorgelibreria.com\/index.php\/categoria-producto\/libreria-escolar\/"},{"label":"TEMPERAS","link":"https:\/\/sanjorgelibreria.com\/index.php\/categoria-producto\/libreria-escolar\/temperas-libreria-escolar\/"},{"label":"EN CAJAS","link":"https:\/\/sanjorgelibreria.com\/index.php\/categoria-producto\/libreria-escolar\/temperas-libreria-escolar\/en-cajas\/"},{"label":"TEMPERA ALBA CLASICO X UNIDAD COLOR NEGRA","link":"https:\/\/sanjorgelibreria.com\/index.php\/producto\/tempera-alba-clasico-x-unidad-color-negra\/"}],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/sanjorgelibreria.com\/index.php\/wp-json\/wp\/v2\/product\/3539","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sanjorgelibreria.com\/index.php\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/sanjorgelibreria.com\/index.php\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":1,"href":"https:\/\/sanjorgelibreria.com\/index.php\/wp-json\/wp\/v2\/product\/3539\/revisions"}],"predecessor-version":[{"id":9609,"href":"https:\/\/sanjorgelibreria.com\/index.php\/wp-json\/wp\/v2\/product\/3539\/revisions\/9609"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sanjorgelibreria.com\/index.php\/wp-json\/wp\/v2\/media\/9604"}],"wp:attachment":[{"href":"https:\/\/sanjorgelibreria.com\/index.php\/wp-json\/wp\/v2\/media?parent=3539"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/sanjorgelibreria.com\/index.php\/wp-json\/wp\/v2\/product_brand?post=3539"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/sanjorgelibreria.com\/index.php\/wp-json\/wp\/v2\/product_cat?post=3539"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/sanjorgelibreria.com\/index.php\/wp-json\/wp\/v2\/product_tag?post=3539"},{"taxonomy":"berocket_brand","embeddable":true,"href":"https:\/\/sanjorgelibreria.com\/index.php\/wp-json\/wp\/v2\/berocket_brand?post=3539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}